{"id":249,"date":"2019-06-15T18:59:28","date_gmt":"2019-06-15T16:59:28","guid":{"rendered":"http:\/\/www2.gaiadis.fr\/?p=249"},"modified":"2019-06-15T19:09:09","modified_gmt":"2019-06-15T17:09:09","slug":"le-risque-financier-des-actifs-echoues-stranded-assets","status":"publish","type":"post","link":"https:\/\/www2.gaiadis.fr\/en\/le-risque-financier-des-actifs-echoues-stranded-assets\/","title":{"rendered":"Le risque financier des actifs \u00e9chou\u00e9s (\u00ab stranded assets \u00bb)"},"content":{"rendered":"<h2>Un quart des \u00e9nergies fossiles utilisables<\/h2>\n<p>Nous disposons de plus de r\u00e9serves d&#8217;\u00e9nergies fossiles que nous ne pourrons en consommer si nous voulons limiter le r\u00e9chauffement \u00e0 +2\u00b0C \u00e0 la fin du si\u00e8cle: un quart seulement des r\u00e9serves d&#8217;\u00e9nergies fossiles pour ne pas d\u00e9passer notre \u00ab budget carbone \u00bb jusqu&#8217;en 2100.<br \/>\nCeci expose les actifs li\u00e9s aux \u00e9nergies fossiles \u00e0 un risque financier de d\u00e9pr\u00e9ciation radicale, d&#8217;o\u00f9 l&#8217;expression d&#8217;actifs \u00e9chou\u00e9s (comme les baleines sur la gr\u00e8ve) ou de &#8220;stranded assets&#8221;.<\/p>\n<h2>Comment arrive-t-on \u00e0 &#8220;un quart&#8221;?<\/h2>\n<p>Selon les calculs du GIEC, pour respecter les +2\u00b0C en 2100, nos \u00e9missions \u00e0 venir ne doivent pas d\u00e9passer la moiti\u00e9 de celles de 1850 \u00e0 2014, soit 700 milliards de tonnes de CO2 : la moiti\u00e9 des 1400 milliards de tonnes de CO2 produits depuis 1850 par la combustion de 180 milliards de &#8220;tep&#8221; tonne \u00e9quivalent p\u00e9trole de charbon, 180 Gtep de p\u00e9trole, 90 Gtep de gaz.<\/p>\n<p>La combustion des r\u00e9serves fossiles prouv\u00e9es publi\u00e9es en 2014 produirait elle 3000 milliards de tonnes de CO2 ( provenant de 430 Gtep de charbon, 240 de p\u00e9trole, 170 gaz).<\/p>\n<p>Notre &#8220;budget&#8221; de 700 milliards de tonnes de CO2 compatible avec l&#8217;objectif des +2\u00b0C en 2100, est donc \u00e0 comparer au 3000 milliards de tonnes &#8220;en r\u00e9serve&#8221; soit \u00e0 peine un quart&#8230;<\/p>\n<p><em>La pr\u00e9sentation de ce calcul est tir\u00e9e de &#8220;Dormez tranquille jusqu&#8217;en 2100&#8221; de JM Jancovici<br \/>\n<img loading=\"lazy\" class=\"wp-image-300 aligncenter\" src=\"http:\/\/gaiadis.fr\/wp-content\/uploads\/2016\/12\/dormez-2100.jpg\" alt=\"\" width=\"102\" height=\"155\" \/><br \/>\n<\/em><\/p>\n<h2>28 000 milliards de dollars de &#8220;stranded assets&#8221;<\/h2>\n<p>Pour le <a href=\"http:\/\/www.keplercheuvreux.com\" target=\"_blank\" rel=\"noopener noreferrer\">cabinet financier Kepler Cheuvreux<\/a>\u00a0en f\u00e9vrier 2016, le montant des pertes que subiraient dans les vingt ans \u00e0 venir les acteurs des \u00e9nergies fossiles ( charbon , gaz, p\u00e9trole ) si les gouvernements s&#8217;accordaient pour limiter r\u00e9ellement le r\u00e9chauffement \u00e0 +2\u00b0C est de<br \/>\n28 000 milliards de dollars.<\/p>\n<h2>A la Banque d&#8217;Angleterre<\/h2>\n<p>En septembre 2015 le gouverneur de la Banque d&#8217;Angleterre Mark Carney , <a href=\"http:\/\/www.bankofengland.co.uk\/publications\/Pages\/speeches\/2015\/844.aspx\" target=\"_blank\" rel=\"noopener noreferrer\">lors d&#8217;un discours aux Lloyds<\/a> a alert\u00e9 les investisseurs financiers, sur le fait qu&#8217;ils sous-estiment les pertes li\u00e9es au r\u00e9chauffement climatique \u00ab potentiellement gigantesques \u00bb, par leurs effets, mais aussi par suite de pertes de valeurs des actifs li\u00e9s aux combustibles fossiles qui ne seront pas consommables.<br \/>\n<iframe loading=\"lazy\" title=\"Breaking the tragedy of the horizon \u2013 climate change and financial stability - speech by Mark Carney\" width=\"678\" height=\"381\" src=\"https:\/\/www.youtube.com\/embed\/V5c-eqNxeSQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><br \/>\nVoir aussi<a href=\"https:\/\/www.ft.com\/content\/622de3da-66e6-11e5-97d0-1456a776a4f5\" target=\"_blank\" rel=\"noopener noreferrer\"> cet article du Financial Times<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un quart des \u00e9nergies fossiles utilisables Nous disposons de plus de r\u00e9serves d&#8217;\u00e9nergies fossiles que nous ne pourrons en consommer si nous voulons limiter le r\u00e9chauffement \u00e0 +2\u00b0C \u00e0 la fin du si\u00e8cle: un quart seulement des r\u00e9serves d&#8217;\u00e9nergies fossiles pour ne pas d\u00e9passer notre \u00ab budget carbone \u00bb jusqu&#8217;en 2100. Ceci expose les actifs [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[8,9],"tags":[],"translation":{"provider":"WPGlobus","version":"3.0.1","language":"en","enabled_languages":["fr","en"],"languages":{"fr":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/www2.gaiadis.fr\/en\/wp-json\/wp\/v2\/posts\/249"}],"collection":[{"href":"https:\/\/www2.gaiadis.fr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www2.gaiadis.fr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www2.gaiadis.fr\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www2.gaiadis.fr\/en\/wp-json\/wp\/v2\/comments?post=249"}],"version-history":[{"count":1,"href":"https:\/\/www2.gaiadis.fr\/en\/wp-json\/wp\/v2\/posts\/249\/revisions"}],"predecessor-version":[{"id":250,"href":"https:\/\/www2.gaiadis.fr\/en\/wp-json\/wp\/v2\/posts\/249\/revisions\/250"}],"wp:attachment":[{"href":"https:\/\/www2.gaiadis.fr\/en\/wp-json\/wp\/v2\/media?parent=249"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www2.gaiadis.fr\/en\/wp-json\/wp\/v2\/categories?post=249"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www2.gaiadis.fr\/en\/wp-json\/wp\/v2\/tags?post=249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}